{"id":5059,"date":"2024-12-31T22:23:11","date_gmt":"2024-12-31T21:23:11","guid":{"rendered":"https:\/\/bernissartlac.be\/?post_type=hb_accommodation&#038;p=5059"},"modified":"2026-04-17T16:49:51","modified_gmt":"2026-04-17T14:49:51","slug":"emplacement-6","status":"publish","type":"hb_accommodation","link":"https:\/\/bernissartlac.be\/nl\/hb_accommodation\/emplacement-6\/","title":{"rendered":"Locatie 6"},"content":{"rendered":"","protected":false},"featured_media":51478,"template":"","class_list":["post-5059","hb_accommodation","type-hb_accommodation","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emplacement 6 - Lac de Bernissart<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bernissartlac.be\/nl\/hb_accommodation\/emplacement-6\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emplacement 6 - Lac de Bernissart\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bernissartlac.be\/nl\/hb_accommodation\/emplacement-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Lac de Bernissart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T14:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bernissartlac.be\/wp-content\/uploads\/2026\/04\/LAC-de-Bernissart-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/\",\"url\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/\",\"name\":\"Emplacement 6 - Lac de Bernissart\",\"isPartOf\":{\"@id\":\"https:\/\/bernissartlac.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-12-31T21:23:11+00:00\",\"dateModified\":\"2026-04-17T14:49:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/bernissartlac.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Types d&#039;h\u00e9bergement\",\"item\":\"https:\/\/bernissartlac.be\/hb_accommodation\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Emplacement 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bernissartlac.be\/#website\",\"url\":\"https:\/\/bernissartlac.be\/\",\"name\":\"Lac de Bernissart\",\"description\":\"Un lieu sp\u00e9cialement am\u00e9nag\u00e9 pour les amateurs de p\u00eache !\",\"publisher\":{\"@id\":\"https:\/\/bernissartlac.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bernissartlac.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bernissartlac.be\/#organization\",\"name\":\"Lac de Bernissart\",\"url\":\"https:\/\/bernissartlac.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\/\/bernissartlac.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bernissartlac.be\/wp-content\/uploads\/2023\/03\/Bernissart-Lac-Logo.png\",\"contentUrl\":\"https:\/\/bernissartlac.be\/wp-content\/uploads\/2023\/03\/Bernissart-Lac-Logo.png\",\"width\":308,\"height\":199,\"caption\":\"Lac de Bernissart\"},\"image\":{\"@id\":\"https:\/\/bernissartlac.be\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emplacement 6 - Lac de Bernissart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bernissartlac.be\/nl\/hb_accommodation\/emplacement-6\/","og_locale":"nl_BE","og_type":"article","og_title":"Emplacement 6 - Lac de Bernissart","og_url":"https:\/\/bernissartlac.be\/nl\/hb_accommodation\/emplacement-6\/","og_site_name":"Lac de Bernissart","article_modified_time":"2026-04-17T14:49:51+00:00","og_image":[{"width":2500,"height":1645,"url":"https:\/\/bernissartlac.be\/wp-content\/uploads\/2026\/04\/LAC-de-Bernissart-06.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/","url":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/","name":"Emplacement 6 - Lac de Bernissart","isPartOf":{"@id":"https:\/\/bernissartlac.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage"},"image":{"@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-12-31T21:23:11+00:00","dateModified":"2026-04-17T14:49:51+00:00","breadcrumb":{"@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/bernissartlac.be\/hb_accommodation\/emplacement-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bernissartlac.be\/"},{"@type":"ListItem","position":2,"name":"Types d&#039;h\u00e9bergement","item":"https:\/\/bernissartlac.be\/hb_accommodation\/"},{"@type":"ListItem","position":3,"name":"Emplacement 6"}]},{"@type":"WebSite","@id":"https:\/\/bernissartlac.be\/#website","url":"https:\/\/bernissartlac.be\/","name":"Het Bernissartmeer","description":"Een plek speciaal ontworpen voor sportvissers!","publisher":{"@id":"https:\/\/bernissartlac.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bernissartlac.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/bernissartlac.be\/#organization","name":"Het Bernissartmeer","url":"https:\/\/bernissartlac.be\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/bernissartlac.be\/#\/schema\/logo\/image\/","url":"https:\/\/bernissartlac.be\/wp-content\/uploads\/2023\/03\/Bernissart-Lac-Logo.png","contentUrl":"https:\/\/bernissartlac.be\/wp-content\/uploads\/2023\/03\/Bernissart-Lac-Logo.png","width":308,"height":199,"caption":"Lac de Bernissart"},"image":{"@id":"https:\/\/bernissartlac.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/hb_accommodation\/5059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/hb_accommodation"}],"about":[{"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/types\/hb_accommodation"}],"version-history":[{"count":1,"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/hb_accommodation\/5059\/revisions"}],"predecessor-version":[{"id":5060,"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/hb_accommodation\/5059\/revisions\/5060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/bernissartlac.be\/nl\/wp-json\/wp\/v2\/media?parent=5059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}